{"id":545,"date":"2022-08-22T09:18:00","date_gmt":"2022-08-22T12:18:00","guid":{"rendered":"https:\/\/devlooper.blog.br\/\/?p=545"},"modified":"2022-09-12T09:42:56","modified_gmt":"2022-09-12T12:42:56","slug":"o-que-e-low-code-no-code","status":"publish","type":"post","link":"https:\/\/www.locaweb.com.br\/blog\/temas\/codigo-aberto\/o-que-e-low-code-no-code\/","title":{"rendered":"Low-code e no-code: o que h\u00e1 por tr\u00e1s dessas abordagens?"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Fala galera, beleza com voc\u00eas? Aqui \u00e9 o <a href=\"https:\/\/twitter.com\/pokemaobr\">pokemaobr<\/a> novamente com mais um artigo para voc\u00eas, e hoje, trago um tema muito falado ultimamente, que \u00e9 Low-code e No-code.<\/em><\/p>\n\n\n\n<p>Muitas vezes quando uma pessoa dev fala sobre esse tema, temos a ideia que iremos discutir se <strong>low-code ou no-code<\/strong> \u00e9 programa\u00e7\u00e3o ou n\u00e3o. Mas essa n\u00e3o \u00e9 uma discuss\u00e3o aqui, at\u00e9 porque temos a mesma discuss\u00e3o sobre se<strong> desenvolver com HTML<\/strong> \u00e9 programa\u00e7\u00e3o ou n\u00e3o. A quest\u00e3o que temos que falar \u00e9: em que tipo de solu\u00e7\u00f5es pode ser interessante usar esse tipo de abordagem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O que \u00e9 Low-code e No-code?<\/strong><\/h2>\n\n\n\n<p>Para quem n\u00e3o sabe: low-code \u00e9 basicamente um jeito de desenvolver utilizando pouco (low-code) ou nenhum c\u00f3digo (no-code). Em geral se utiliza interfaces visuais onde a pessoa constr\u00f3i os aplicativos utilizando l\u00f3gica b\u00e1sica e alguns recursos drag-and-drop (arrastar e soltar). <\/p>\n\n\n\n<p>No <strong>desenvolvimento low-code<\/strong> a pessoa precisa ter um pouco de no\u00e7\u00e3o de desenvolvimento, enquanto no no-code uma pessoa totalmente leiga em programa\u00e7\u00e3o consegue desenvolver.<\/p>\n\n\n\n<p>N\u00f3s, como pessoas dev, temos que entender que nem todas as pessoas precisam de conhecimentos avan\u00e7ados ou realmente de l\u00f3gicas complexas para resolver os seus problemas. Muitas vezes elas precisam apenas de algo para automatizar uma tarefa e evitar o esfor\u00e7o repetitivo. E, \u00e9 exatamente essa a proposta dessas plataformas: levar para pessoas com pouco ou nenhum <a href=\"https:\/\/blog.locaweb.com.br\/temas\/codigo-aberto\/conheca-3-ferramentas-e-sites-que-avaliam-a-qualidade-do-codigo\/\">conhecimento em c\u00f3digo<\/a> uma maneira de resolver os seus problemas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Como funciona o Low-code e no-code?<\/strong><\/h2>\n\n\n\n<p>O tipo de abordagem que o low-code\/no-code aborda \u00e9 interessante at\u00e9 para trazer mais pessoas para o mundo dev. Embora essas plataformas possam trazer uma <strong>facilidade no desenvolvimento de softwares<\/strong> e aplicativos em geral elas possuem um escopo limitado e para desenvolver maiores customiza\u00e7\u00f5es ser\u00e1 necess\u00e1rio realmente a implementa\u00e7\u00e3o atrav\u00e9s dos<strong> modos padr\u00e3o de desenvolvimento<\/strong>.<\/p>\n\n\n\n<p>Uma <a href=\"https:\/\/blog.locaweb.com.br\/temas\/codigo-aberto\/como-se-tornar-uma-pessoa-dev-mais-produtiva\/\">skill fundamental para toda pessoa dev<\/a> \u00e9 entender um pouco mais a fundo sobre o neg\u00f3cio, e, muitas das vezes utilizando uma abordagem low-code\/no-code, literalmente as pessoas que mais entendem do neg\u00f3cio poder\u00e3o desenvolver o que faz sentido para a \u00e1rea dela sem a necessidade de ter uma <strong>equipe de desenvolvimento<\/strong> para realizar essa tarefa.<\/p>\n\n\n\n<p>Algumas das \u00e1reas comercialmente falando que utilizam bastante estrat\u00e9gias low-code\/no-code s\u00e3o: RH, Comercial\/Vendas, ERPs\/CRMs, gest\u00e3o de tempo, etc.<\/p>\n\n\n\n<p>Para elucidar um pouco como funciona esse universo, trago alguns exemplos de plataformas low-code\/no-code que podemos utilizar como devs.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Scratch<\/strong><\/h2>\n\n\n\n<p>Esse conceito \u00e9 utilizado por exemplo no <a href=\"https:\/\/scratch.mit.edu\/\">Scratch<\/a> (um projeto do MIT) para ensinar pessoas a entenderem l\u00f3gica de programa\u00e7\u00e3o. Nele a pessoa utiliza blocos de comandos para fazer com que o gato realize algumas a\u00e7\u00f5es, fale, mude de apar\u00eancia, etc.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"602\" height=\"332\" src=\"https:\/\/www.locaweb.com.br\/blog\/wp-content\/uploads\/2018\/12\/fluxo-do-scratch.jpg\" alt=\"fluxo do scratch low-code no-code\" class=\"wp-image-35849\"\/><figcaption>Exemplo de fluxo do Scratch<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Abordagens como o Scratch s\u00e3o interessantes, j\u00e1 que \u00e9 poss\u00edvel observar a l\u00f3gica acontecendo visualmente, o que <strong>facilita e muito o aprendizado de l\u00f3gica<\/strong>, que eu considero algo fundamental na aprendizagem no universo da programa\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>MIT APP Inventor<\/strong><\/h2>\n\n\n\n<p>Quando falamos de desenvolvimento para aplicativos m\u00f3veis, por exemplo, existe uma outra plataforma, tamb\u00e9m do MIT, que ajuda na prototipa\u00e7\u00e3o e desenvolvimento utilizando low-code. O <a href=\"https:\/\/appinventor.mit.edu\/\">MIT App Inventor<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"602\" height=\"251\" src=\"https:\/\/www.locaweb.com.br\/blog\/wp-content\/uploads\/2018\/12\/MIT-app-inventor.jpg\" alt=\"MIT app inventor low-code no-code\" class=\"wp-image-35850\"\/><figcaption>MIT App Inventor<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Nele voc\u00ea pode utilizar diversas funcionalidades pr\u00e9 moldadas para desenvolver um aplicativo totalmente funcional para smartphones Android, iPhones e\/ou tablets Android\/iOS e test\u00e1-lo nos mais diferentes modelos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Node-RED<\/strong><\/h2>\n\n\n\n<p>No <strong>mundo do desenvolvimento<\/strong> uma plataforma muito conhecida de low-code para conectar dispositivos de hardware, APIs e outros servi\u00e7os online de maneira visual e intuitiva \u00e9 o <a href=\"https:\/\/nodered.org\/\">Node-RED<\/a>. Ele fornece um editor baseado em navegador que facilita a conex\u00e3o de fluxos usando uma variedade de n\u00f3s. Foi desenvolvido em Node.js e voc\u00ea pode criar coisas localmente, em um dispositivo como Raspberry Pi, ou na nuvem.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"602\" height=\"291\" src=\"https:\/\/www.locaweb.com.br\/blog\/wp-content\/uploads\/2018\/12\/node-red.jpg\" alt=\"node-red low-code no-code\" class=\"wp-image-35851\"\/><\/figure>\n<\/div>\n\n\n<p>O desenvolvimento utilizando o Node-RED \u00e9 baseado em n\u00f3s que basicamente s\u00e3o de 3 tipos: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>n\u00f3s de entrada:<\/strong> onde \u00e9 permitido inser\u00e7\u00e3o de dados em uma determinada aplica\u00e7\u00e3o;<\/li><li><strong>n\u00f3s de sa\u00edda:<\/strong> onde \u00e9 permitido o envio de dados para fora de uma aplica\u00e7\u00e3o;<\/li><li><strong>n\u00f3s de processamento:<\/strong> onde \u00e9 feito a manipula\u00e7\u00e3o dos dados.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Plataformas Comerciais<\/strong><\/h2>\n\n\n\n<p>Quando falamos das plataformas de low-code\/no-code utilizada em larga escala comercialmente. De acordo com o Gartner 2021, o quadrante m\u00e1gico \u00e9 o seguinte:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.locaweb.com.br\/blog\/wp-content\/uploads\/2018\/12\/gartner-481x500.jpg\" alt=\"gartner\" class=\"wp-image-35854\"\/><\/figure>\n<\/div>\n\n\n<p>Sendo as categorias:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Challengers &#8211; Oracle, Appian, Pega<\/li><li>Leaders &#8211; OutSystems, Mendix, Microsoft, Salesforce<\/li><li>Niche Players &#8211; Kintone, Newgen, Quickbase, Creatio<\/li><\/ul>\n\n\n\n<p>Bem, desejo que voc\u00eas tenham entendido um pouco como funcionam algumas plataformas low-code\/no-code e o motivo das pessoas utilizarem. E antes de falarmos mal de uma tecnologia, temos que entender tudo que est\u00e1 por tr\u00e1s e o que aquela tecnologia resolve. Um grande abra\u00e7o para voc\u00eas, at\u00e9 mais.<\/p>\n\n\n\n<div class=\"user-cta-block\" style=\"background-color:#2E333C;\"><p>Conhe\u00e7a a VPS Locaweb e tenha a melhor performance para o seu projeto!<\/p><a class=\"user-cta\" style=\"background-color: #F00842\n;\" href=\"https:\/\/www.locaweb.com.br\/cloud\/vps-locaweb\/?utm_source=blog&#038;utm_medium=own&#038;utm_campaign=blog-vps-low-code&#038;utm_id=blog-vendas\" target=\"_blank\" rel=\"noopener\">CLIQUE AQUI<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Fala galera, beleza com voc\u00eas? Aqui \u00e9 o pokemaobr novamente com mais um artigo para voc\u00eas, e hoje, trago um tema muito falado ultimamente, que \u00e9 Low-code e No-code. Muitas vezes quando uma pessoa dev fala sobre esse tema, temos a ideia que iremos discutir se low-code ou no-code \u00e9 programa\u00e7\u00e3o ou n\u00e3o. Mas essa [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":35855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-545","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-codigo-aberto"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/comments?post=545"}],"version-history":[{"count":6,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions"}],"predecessor-version":[{"id":37711,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/posts\/545\/revisions\/37711"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/media\/35855"}],"wp:attachment":[{"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/media?parent=545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/categories?post=545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.locaweb.com.br\/blog\/wp-json\/wp\/v2\/tags?post=545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}